{"id":10434,"date":"2026-07-08T13:23:15","date_gmt":"2026-07-08T11:23:15","guid":{"rendered":"https:\/\/genekam.de\/?page_id=10434"},"modified":"2026-07-08T13:30:24","modified_gmt":"2026-07-08T11:30:24","slug":"k197-borrelia-burgdorferi-genotyping-pcr-kit","status":"publish","type":"page","link":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/","title":{"rendered":"K197 Borrelia burgdorferi genotyping PCR Kit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10434\" class=\"elementor elementor-10434\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-815c892 e-flex e-con-boxed e-con e-parent\" data-id=\"815c892\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60dccfe elementor-widget elementor-widget-eael-advanced-data-table\" data-id=\"60dccfe\" data-element_type=\"widget\" data-widget_type=\"eael-advanced-data-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ea-advanced-data-table-wrap\" data-id=\"60dccfe\"><div class=\"ea-advanced-data-table-search-wrap ea-advanced-data-table-search-right\"><input type=\"search\" placeholder=\"Search\" class=\"ea-advanced-data-table-search\"><\/div><div class=\"ea-advanced-data-table-wrap-inner\">\n                <table class=\"ea-advanced-data-table ea-advanced-data-table-static ea-advanced-data-table-60dccfe ea-advanced-data-table-sortable ea-advanced-data-table-paginated ea-advanced-data-table-searchable\" data-id=\"60dccfe\" data-items-per-page=\"10\"><thead><tr><th><p>Cat. No.<\/p><\/th><th><p>Name of ready-to-use PCR kit<\/p><\/th><th><p>Storage<\/p><\/th><th><p>DOC<\/p><\/th><th><p>Amount<\/p><\/th><th><p>Price*<\/p><\/th><\/tr><\/thead><tbody><tr><td><p><span>K197<\/span><\/p><\/td><td><p><span>Borrelia burgdorferi genotyping<\/span><\/p><\/td><td><p><span>-20\u00b0C<\/span><\/p><\/td><td><p><br><\/p><\/td><td><p><span>100<\/span><\/p><\/td><td><p><span>619\u20ac<\/span><\/p><\/td><\/tr><\/tbody><\/table>\n            <\/div><div class=\"ea-advanced-data-table-pagination ea-advanced-data-table-pagination-button clearfix\"><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"Cat. No. Name of ready-to-use PCR kit Storage DOC Amount Price* K197 Borrelia burgdorferi genotyping -20\u00b0C 100 619\u20ac","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10434","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG\" \/>\n<meta property=\"og:description\" content=\"Cat. No. Name of ready-to-use PCR kit Storage DOC Amount Price* K197 Borrelia burgdorferi genotyping -20\u00b0C 100 619\u20ac\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/\" \/>\n<meta property=\"og:site_name\" content=\"Genekam Biotechnology AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T11:30:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/\",\"url\":\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/\",\"name\":\"K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG\",\"isPartOf\":{\"@id\":\"https:\/\/genekam.de\/#website\"},\"datePublished\":\"2026-07-08T11:23:15+00:00\",\"dateModified\":\"2026-07-08T11:30:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/genekam.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K197 Borrelia burgdorferi genotyping PCR Kit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/genekam.de\/#website\",\"url\":\"https:\/\/genekam.de\/\",\"name\":\"Genekam Biotechnology AG\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/genekam.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/","og_locale":"de_DE","og_type":"article","og_title":"K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG","og_description":"Cat. No. Name of ready-to-use PCR kit Storage DOC Amount Price* K197 Borrelia burgdorferi genotyping -20\u00b0C 100 619\u20ac","og_url":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/","og_site_name":"Genekam Biotechnology AG","article_modified_time":"2026-07-08T11:30:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/","url":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/","name":"K197 Borrelia burgdorferi genotyping PCR Kit - Genekam Biotechnology AG","isPartOf":{"@id":"https:\/\/genekam.de\/#website"},"datePublished":"2026-07-08T11:23:15+00:00","dateModified":"2026-07-08T11:30:24+00:00","breadcrumb":{"@id":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/genekam.de\/index.php\/k197-borrelia-burgdorferi-genotyping-pcr-kit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/genekam.de\/"},{"@type":"ListItem","position":2,"name":"K197 Borrelia burgdorferi genotyping PCR Kit"}]},{"@type":"WebSite","@id":"https:\/\/genekam.de\/#website","url":"https:\/\/genekam.de\/","name":"Genekam Biotechnology AG","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genekam.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/pages\/10434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/comments?post=10434"}],"version-history":[{"count":4,"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/pages\/10434\/revisions"}],"predecessor-version":[{"id":10438,"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/pages\/10434\/revisions\/10438"}],"wp:attachment":[{"href":"https:\/\/genekam.de\/index.php\/wp-json\/wp\/v2\/media?parent=10434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}